{"id":30,"count":88,"description":"","link":"https:\/\/espace-personnels.lfitokyo.org\/index.php\/category\/securite\/","name":"S\u00e9curit\u00e9","slug":"securite","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/espace-personnels.lfitokyo.org\/index.php\/wp-json\/wp\/v2\/categories\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espace-personnels.lfitokyo.org\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/espace-personnels.lfitokyo.org\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/espace-personnels.lfitokyo.org\/index.php\/wp-json\/wp\/v2\/posts?categories=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}